{"id":3136,"date":"2026-01-16T14:29:04","date_gmt":"2026-01-16T20:29:04","guid":{"rendered":"https:\/\/amacuzac.gob.mx\/2025-2027\/?p=3136"},"modified":"2026-03-25T14:36:07","modified_gmt":"2026-03-25T20:36:07","slug":"informe-de-la-procuraduria-de-la-defensa-del-menor-y-de-la-familia","status":"publish","type":"post","link":"https:\/\/amacuzac.gob.mx\/2025-2027\/informe-de-la-procuraduria-de-la-defensa-del-menor-y-de-la-familia\/","title":{"rendered":"Informe de la procuradur\u00eda de la defensa del menor y de la familia"},"content":{"rendered":"<div class=\"xdj266r x14z9mp xat24cr x1lziwak x1vvkbs x126k92a\">\n<div dir=\"auto\">Como parte de la continuidad de los videos del Informe de Gobierno presentado el pasado mes de diciembre, la Procuradur\u00eda de la Defensa del Menor y la Familia de Amacuzac, bajo el liderazgo de nuestro amigo No\u00e9 Reynoso, fortaleci\u00f3 durante 2025 la protecci\u00f3n de los derechos de ni\u00f1as, ni\u00f1os, adolescentes y familias.<\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Se brindaron asesor\u00edas jur\u00eddicas, conciliaciones y acompa\u00f1amiento legal, adem\u00e1s de acciones preventivas con pl\u00e1ticas y talleres sobre violencia familiar, bullying y derechos de la ni\u00f1ez, beneficiando a menores, estudiantes y padres de familia.<\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Acciones que reafirman el compromiso del Ayuntamiento de Amacuzac con la justicia, el bienestar y la protecci\u00f3n integral de quienes m\u00e1s lo necesitan.<\/div>\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3137\" src=\"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-content\/uploads\/2026\/03\/Captura-de-pantalla-2026-03-25-143222-300x170.png\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-content\/uploads\/2026\/03\/Captura-de-pantalla-2026-03-25-143222-300x170.png 300w, https:\/\/amacuzac.gob.mx\/2025-2027\/wp-content\/uploads\/2026\/03\/Captura-de-pantalla-2026-03-25-143222-1024x579.png 1024w, https:\/\/amacuzac.gob.mx\/2025-2027\/wp-content\/uploads\/2026\/03\/Captura-de-pantalla-2026-03-25-143222-768x435.png 768w, https:\/\/amacuzac.gob.mx\/2025-2027\/wp-content\/uploads\/2026\/03\/Captura-de-pantalla-2026-03-25-143222-678x381.png 678w, https:\/\/amacuzac.gob.mx\/2025-2027\/wp-content\/uploads\/2026\/03\/Captura-de-pantalla-2026-03-25-143222.png 1087w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">Como parte de la continuidad de los videos del Informe de Gobierno presentado el pasado mes de diciembre, la Procuradur\u00eda de la Defensa del Menor y la Familia de Amacuzac, bajo el liderazgo de nuestro <a class=\"mh-excerpt-more\" href=\"https:\/\/amacuzac.gob.mx\/2025-2027\/informe-de-la-procuraduria-de-la-defensa-del-menor-y-de-la-familia\/\" title=\"Informe de la procuradur\u00eda de la defensa del menor y de la familia\">Leer m\u00e1s&#8230;<\/a><\/div>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-3136","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-general"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/posts\/3136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/comments?post=3136"}],"version-history":[{"count":1,"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/posts\/3136\/revisions"}],"predecessor-version":[{"id":3138,"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/posts\/3136\/revisions\/3138"}],"wp:attachment":[{"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/media?parent=3136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/categories?post=3136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/tags?post=3136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}