{"id":3155,"date":"2026-01-21T08:31:41","date_gmt":"2026-01-21T14:31:41","guid":{"rendered":"https:\/\/amacuzac.gob.mx\/2025-2027\/?p=3155"},"modified":"2026-03-26T08:34:43","modified_gmt":"2026-03-26T14:34:43","slug":"como-continuacion-de-los-videos-del-informe-de-gobierno-presentado-el-pasado-mes-de-diciembre-la-direccion-de-educacion-cultura-y-deporte","status":"publish","type":"post","link":"https:\/\/amacuzac.gob.mx\/2025-2027\/como-continuacion-de-los-videos-del-informe-de-gobierno-presentado-el-pasado-mes-de-diciembre-la-direccion-de-educacion-cultura-y-deporte\/","title":{"rendered":"Como continuaci\u00f3n de los videos del Informe de Gobierno presentado el pasado mes de diciembre, la Direcci\u00f3n de Educaci\u00f3n, Cultura y Deporte"},"content":{"rendered":"<div class=\"xdj266r x14z9mp xat24cr x1lziwak x1vvkbs x126k92a\">\n<div dir=\"auto\">Como continuaci\u00f3n de los videos del Informe de Gobierno presentado el pasado mes de diciembre, la Direcci\u00f3n de Educaci\u00f3n, Cultura y Deporte de Amacuzac, bajo el liderazgo de nuestro amigo No\u00e9 Reynoso, impuls\u00f3 durante 2025 acciones que fortalecieron la educaci\u00f3n, la cultura y el deporte en el municipio.<\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Se brind\u00f3 apoyo a bibliotecas y escuelas, se promovieron oportunidades educativas, actividades culturales y tradiciones, adem\u00e1s de la rehabilitaci\u00f3n de espacios deportivos y la realizaci\u00f3n de torneos, entrenamientos y exhibiciones que beneficiaron a ni\u00f1as, ni\u00f1os, j\u00f3venes y familias de diversas comunidades.<\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Acciones que reflejan el compromiso de seguir construyendo un Amacuzac m\u00e1s preparado, activo y unido.<\/div>\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3156\" src=\"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-content\/uploads\/2026\/03\/Captura-de-pantalla-2026-03-26-083227-300x166.png\" alt=\"\" width=\"300\" height=\"166\" srcset=\"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-content\/uploads\/2026\/03\/Captura-de-pantalla-2026-03-26-083227-300x166.png 300w, https:\/\/amacuzac.gob.mx\/2025-2027\/wp-content\/uploads\/2026\/03\/Captura-de-pantalla-2026-03-26-083227-1024x568.png 1024w, https:\/\/amacuzac.gob.mx\/2025-2027\/wp-content\/uploads\/2026\/03\/Captura-de-pantalla-2026-03-26-083227-768x426.png 768w, https:\/\/amacuzac.gob.mx\/2025-2027\/wp-content\/uploads\/2026\/03\/Captura-de-pantalla-2026-03-26-083227.png 1093w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">Como continuaci\u00f3n de los videos del Informe de Gobierno presentado el pasado mes de diciembre, la Direcci\u00f3n de Educaci\u00f3n, Cultura y Deporte de Amacuzac, bajo el liderazgo de nuestro amigo No\u00e9 Reynoso, impuls\u00f3 durante 2025 <a class=\"mh-excerpt-more\" href=\"https:\/\/amacuzac.gob.mx\/2025-2027\/como-continuacion-de-los-videos-del-informe-de-gobierno-presentado-el-pasado-mes-de-diciembre-la-direccion-de-educacion-cultura-y-deporte\/\" title=\"Como continuaci\u00f3n de los videos del Informe de Gobierno presentado el pasado mes de diciembre, la Direcci\u00f3n de Educaci\u00f3n, Cultura y Deporte\">Leer m\u00e1s&#8230;<\/a><\/div>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-3155","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-general"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/posts\/3155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/comments?post=3155"}],"version-history":[{"count":1,"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/posts\/3155\/revisions"}],"predecessor-version":[{"id":3157,"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/posts\/3155\/revisions\/3157"}],"wp:attachment":[{"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/media?parent=3155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/categories?post=3155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amacuzac.gob.mx\/2025-2027\/wp-json\/wp\/v2\/tags?post=3155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}